{"id":106,"count":2,"description":"","link":"https:\/\/liferunsweet.com\/blog\/tag\/streusel\/","name":"Streusel","slug":"streusel","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Streusel Archives - Life Run Sweet<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/liferunsweet.com\/blog\/tag\/streusel\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Streusel Archives - Life Run Sweet\" \/>\n<meta property=\"og:url\" content=\"https:\/\/liferunsweet.com\/blog\/tag\/streusel\/\" \/>\n<meta property=\"og:site_name\" content=\"Life Run Sweet\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/liferunsweet.com\\\/blog\\\/tag\\\/streusel\\\/\",\"url\":\"https:\\\/\\\/liferunsweet.com\\\/blog\\\/tag\\\/streusel\\\/\",\"name\":\"Streusel Archives - Life Run Sweet\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/liferunsweet.com\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/liferunsweet.com\\\/blog\\\/tag\\\/streusel\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/liferunsweet.com\\\/blog\\\/tag\\\/streusel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/liferunsweet.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Streusel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/liferunsweet.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/liferunsweet.com\\\/blog\\\/\",\"name\":\"Life Run Sweet\",\"description\":\"Life, Running, and Desserts\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/liferunsweet.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Streusel Archives - Life Run Sweet","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/liferunsweet.com\/blog\/tag\/streusel\/","og_locale":"en_US","og_type":"article","og_title":"Streusel Archives - Life Run Sweet","og_url":"https:\/\/liferunsweet.com\/blog\/tag\/streusel\/","og_site_name":"Life Run Sweet","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/liferunsweet.com\/blog\/tag\/streusel\/","url":"https:\/\/liferunsweet.com\/blog\/tag\/streusel\/","name":"Streusel Archives - Life Run Sweet","isPartOf":{"@id":"https:\/\/liferunsweet.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/liferunsweet.com\/blog\/tag\/streusel\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/liferunsweet.com\/blog\/tag\/streusel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/liferunsweet.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Streusel"}]},{"@type":"WebSite","@id":"https:\/\/liferunsweet.com\/blog\/#website","url":"https:\/\/liferunsweet.com\/blog\/","name":"Life Run Sweet","description":"Life, Running, and Desserts","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/liferunsweet.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/liferunsweet.com\/blog\/wp-json\/wp\/v2\/tags\/106","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/liferunsweet.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/liferunsweet.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/liferunsweet.com\/blog\/wp-json\/wp\/v2\/posts?tags=106"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}