{"id":1,"count":1,"description":"","link":"https:\/\/liferunsweet.com\/blog\/category\/uncategorized\/","name":"Uncategorized","slug":"uncategorized","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Uncategorized Archives - Life Run Sweet<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/liferunsweet.com\/blog\/category\/uncategorized\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Uncategorized Archives - Life Run Sweet\" \/>\n<meta property=\"og:url\" content=\"https:\/\/liferunsweet.com\/blog\/category\/uncategorized\/\" \/>\n<meta property=\"og:site_name\" content=\"Life Run Sweet\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/liferunsweet.com\\\/blog\\\/category\\\/uncategorized\\\/\",\"url\":\"https:\\\/\\\/liferunsweet.com\\\/blog\\\/category\\\/uncategorized\\\/\",\"name\":\"Uncategorized Archives - Life Run Sweet\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/liferunsweet.com\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/liferunsweet.com\\\/blog\\\/category\\\/uncategorized\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/liferunsweet.com\\\/blog\\\/category\\\/uncategorized\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/liferunsweet.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Uncategorized\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/liferunsweet.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/liferunsweet.com\\\/blog\\\/\",\"name\":\"Life Run Sweet\",\"description\":\"Life, Running, and Desserts\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/liferunsweet.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Uncategorized Archives - Life Run Sweet","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/liferunsweet.com\/blog\/category\/uncategorized\/","og_locale":"en_US","og_type":"article","og_title":"Uncategorized Archives - Life Run Sweet","og_url":"https:\/\/liferunsweet.com\/blog\/category\/uncategorized\/","og_site_name":"Life Run Sweet","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/liferunsweet.com\/blog\/category\/uncategorized\/","url":"https:\/\/liferunsweet.com\/blog\/category\/uncategorized\/","name":"Uncategorized Archives - Life Run Sweet","isPartOf":{"@id":"https:\/\/liferunsweet.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/liferunsweet.com\/blog\/category\/uncategorized\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/liferunsweet.com\/blog\/category\/uncategorized\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/liferunsweet.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Uncategorized"}]},{"@type":"WebSite","@id":"https:\/\/liferunsweet.com\/blog\/#website","url":"https:\/\/liferunsweet.com\/blog\/","name":"Life Run Sweet","description":"Life, Running, and Desserts","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/liferunsweet.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/liferunsweet.com\/blog\/wp-json\/wp\/v2\/categories\/1","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/liferunsweet.com\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/liferunsweet.com\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/liferunsweet.com\/blog\/wp-json\/wp\/v2\/posts?categories=1"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}